{"id":4841,"date":"2021-03-08T16:43:11","date_gmt":"2021-03-08T15:43:11","guid":{"rendered":"http:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20.jpg"},"modified":"2021-03-08T16:43:11","modified_gmt":"2021-03-08T15:43:11","slug":"kagran_2019_20","status":"inherit","type":"attachment","link":"https:\/\/deserteursdenkmal.at\/wordpress\/kagran_2019_20\/","title":{"rendered":"kagran_2019_20"},"author":1,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20.jpg'><img width=\"300\" height=\"146\" src=\"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-300x146.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-300x146.jpg 300w, https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-1024x498.jpg 1024w, https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-768x373.jpg 768w, https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-1536x747.jpg 1536w, https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-500x243.jpg 500w, https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n "},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":778,"file":"2021\/03\/kagran_2019_20.jpg","sizes":{"medium":{"file":"kagran_2019_20-300x146.jpg","width":300,"height":146,"mime_type":"image\/jpeg","source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-300x146.jpg"},"large":{"file":"kagran_2019_20-1024x498.jpg","width":1024,"height":498,"mime_type":"image\/jpeg","source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-1024x498.jpg"},"thumbnail":{"file":"kagran_2019_20-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-150x150.jpg"},"medium_large":{"file":"kagran_2019_20-768x373.jpg","width":768,"height":373,"mime_type":"image\/jpeg","source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-768x373.jpg"},"1536x1536":{"file":"kagran_2019_20-1536x747.jpg","width":1536,"height":747,"mime_type":"image\/jpeg","source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-1536x747.jpg"},"post-thumbnail":{"file":"kagran_2019_20-1000x288.jpg","width":1000,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-1000x288.jpg"},"large-feature":{"file":"kagran_2019_20-1000x288.jpg","width":1000,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-1000x288.jpg"},"small-feature":{"file":"kagran_2019_20-500x243.jpg","width":500,"height":243,"mime_type":"image\/jpeg","source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20-500x243.jpg"},"full":{"file":"kagran_2019_20.jpg","width":1600,"height":778,"mime_type":"image\/jpeg","source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-content\/uploads\/2021\/03\/kagran_2019_20.jpg","_links":{"self":[{"href":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-json\/wp\/v2\/media\/4841"}],"collection":[{"href":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deserteursdenkmal.at\/wordpress\/wp-json\/wp\/v2\/comments?post=4841"}]}}